{"id":11295,"date":"2024-05-14T17:49:24","date_gmt":"2024-05-14T15:49:24","guid":{"rendered":"https:\/\/newbti.spri.eus\/energy\/"},"modified":"2025-01-23T15:43:31","modified_gmt":"2025-01-23T14:43:31","slug":"energy","status":"publish","type":"page","link":"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/specialist-and-sectoral-services\/energy\/","title":{"rendered":"Energy"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_bbd745-d2{margin-bottom:0px;}.kb-row-layout-id11295_bbd745-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_bbd745-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_bbd745-d2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_bbd745-d2{background-image:url('https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2025\/01\/Cabecera_Servicios-sectoriales-min.png');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id11295_bbd745-d2 > .kt-row-layout-overlay{opacity:0.50;background-color:#1e1e1e;mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id11295_bbd745-d2 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_bbd745-d2 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_bbd745-d2 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column11295_5b1b97-1c > .kt-inside-inner-col,.kadence-column11295_5b1b97-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_5b1b97-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_5b1b97-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_5b1b97-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_5b1b97-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_5b1b97-1c{position:relative;}.kadence-column11295_5b1b97-1c, .kt-inside-inner-col > .kadence-column11295_5b1b97-1c:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column11295_5b1b97-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_5b1b97-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_5b1b97-1c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed, .wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed[data-kb-block=\"kb-adv-heading11295_384c50-ed\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed[data-kb-block=\"kb-adv-heading11295_384c50-ed\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed, .wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed[data-kb-block=\"kb-adv-heading11295_384c50-ed\"]{font-size:var(--global-kb-font-size-xl, 3rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed, .wp-block-kadence-advancedheading.kt-adv-heading11295_384c50-ed[data-kb-block=\"kb-adv-heading11295_384c50-ed\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h1 class=\"kt-adv-heading11295_384c50-ed wp-block-kadence-advancedheading has-white-color has-text-color\" data-kb-block=\"kb-adv-heading11295_384c50-ed\">Energy<\/h1>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_a70c29-92{margin-bottom:0px;}.kb-row-layout-id11295_a70c29-92 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_a70c29-92 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_a70c29-92 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_a70c29-92 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_a70c29-92 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_a70c29-92 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_a70c29-92 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column11295_3e5a18-ca > .kt-inside-inner-col,.kadence-column11295_3e5a18-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_3e5a18-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_3e5a18-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_3e5a18-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_3e5a18-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_3e5a18-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_3e5a18-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_3e5a18-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_3e5a18-ca\"><div class=\"kt-inside-inner-col\"><nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span><span><a href=\"https:\/\/basquetrade.spri.eus\/en\/\">Portada<\/a><\/span><\/span><\/p><\/nav>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_87b5ba-65{margin-bottom:0px;}.kb-row-layout-id11295_87b5ba-65 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_87b5ba-65 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_87b5ba-65 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);max-width:1024px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-xl, 4rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_87b5ba-65 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_87b5ba-65 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_87b5ba-65 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_87b5ba-65 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{display:flex;}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:0px solid var(--base);border-bottom:0px solid var(--base);border-left:0px solid var(--base);}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col,.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column11295_e9f3ea-66{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{background-color:var(u002du002dwhite);}.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_e9f3ea-66{text-align:center;}.kadence-column11295_e9f3ea-66{position:relative;}.kadence-column11295_e9f3ea-66, .kt-inside-inner-col > .kadence-column11295_e9f3ea-66:not(.specificity){margin-bottom:0px;}@media all and (max-width: 1024px){.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:0px solid var(--base);border-bottom:0px solid var(--base);border-left:0px solid var(--base);flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column11295_e9f3ea-66{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:0px solid var(--base);border-bottom:0px solid var(--base);border-left:0px solid var(--base);flex-direction:column;justify-content:flex-end;}.kt-row-column-wrap > .kadence-column11295_e9f3ea-66{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_e9f3ea-66 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_e9f3ea-66\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11295_6015f5-87, .wp-block-kadence-advancedheading.kt-adv-heading11295_6015f5-87[data-kb-block=\"kb-adv-heading11295_6015f5-87\"]{font-size:var(--global-kb-font-size-xl, 3rem);font-weight:500;font-style:italic;font-family:'EB Garamond';}.wp-block-kadence-advancedheading.kt-adv-heading11295_6015f5-87 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_6015f5-87[data-kb-block=\"kb-adv-heading11295_6015f5-87\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading11295_6015f5-87 h2_border_center wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_6015f5-87\">Service and specialty<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{border-top:2px solid var(--base);border-right:2px solid var(--base);border-bottom:0px solid var(--base);border-left:2px solid var(--base);}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col,.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{background-color:var(u002du002dwhite);}.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_d5cf4c-10{text-align:center;}.kadence-column11295_d5cf4c-10{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{border-top:2px solid var(--base);border-right:2px solid var(--base);border-bottom:0px solid var(--base);border-left:2px solid var(--base);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_d5cf4c-10 > .kt-inside-inner-col{border-top:2px solid var(--base);border-right:2px solid var(--base);border-bottom:0px solid var(--base);border-left:2px solid var(--base);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_d5cf4c-10\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11295_5e353c-33, .wp-block-kadence-advancedheading.kt-adv-heading11295_5e353c-33[data-kb-block=\"kb-adv-heading11295_5e353c-33\"]{text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading11295_5e353c-33 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_5e353c-33[data-kb-block=\"kb-adv-heading11295_5e353c-33\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading11295_5e353c-33 justify wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_5e353c-33\">The energy sector is one of the strategic cornerstones of the technological and industrial development of the Basque Country, representing 9% of the industrial GDP and employing over 26,000 people in the Basque Country. The Basque companies of the sector cover a wide range, from generating solar and wind power to storage solutions and smart networks. The partnership between industry, technology centres and universities have allowed innovative technologies to be developed and which are positioning the Basque Country as a benchmark in sustainable energy.  <\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_5c7dcc-68{margin-bottom:0px;}.kb-row-layout-id11295_5c7dcc-68 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11295_5c7dcc-68 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11295_5c7dcc-68 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:0px;padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_5c7dcc-68 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_5c7dcc-68 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_5c7dcc-68 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id11295_5c7dcc-68 alignfull has-base-background-color kt-row-has-bg p_center wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column11295_c3a176-0b > .kt-inside-inner-col,.kadence-column11295_c3a176-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_c3a176-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_c3a176-0b > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_c3a176-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_c3a176-0b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_c3a176-0b{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_c3a176-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_c3a176-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_c3a176-0b\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_288895-52{margin-bottom:0px;}.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap{column-gap:32px;row-gap:var(--global-kb-gap-lg, 4rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(40% - ((32px * 2 )\/3)))minmax(0, calc(25% - ((32px * 2 )\/3)))minmax(0, calc(35% - ((32px * 2 )\/3)));}.kb-row-layout-id11295_288895-52 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap{column-gap:88px;row-gap:var(--global-kb-gap-sm, 1rem);padding-right:64px;padding-left:64px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap > *:nth-child(3n of *:not(style)){grid-column:1 \/ -1;}}@media all and (max-width: 767px){.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_288895-52 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_288895-52 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-last-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11295_e18ca6-75 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11295_e18ca6-75 > .kt-inside-inner-col,.kadence-column11295_e18ca6-75 > .kt-inside-inner-col:before{border-top-left-radius:50%;border-top-right-radius:50%;border-bottom-right-radius:50%;border-bottom-left-radius:50%;}.kadence-column11295_e18ca6-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_e18ca6-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_e18ca6-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_e18ca6-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_e18ca6-75{text-align:center;}.kadence-column11295_e18ca6-75{position:relative;}.kadence-column11295_e18ca6-75, .kt-inside-inner-col > .kadence-column11295_e18ca6-75:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column11295_e18ca6-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_e18ca6-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_e18ca6-75\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-11295_f9366f-b8 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.2;font-family:'Source Sans Pro';font-weight:300;text-transform:uppercase;padding-bottom:0px;margin-bottom:0px;}.kb-count-up-11295_f9366f-b8 .kb-count-up-title{text-align:center;}.kb-count-up-11295_f9366f-b8 .kb-count-up-number{color:var(--primary);font-size:80px;font-family:Raleway;font-weight:500;}@media all and (max-width: 1024px){.kb-count-up-11295_f9366f-b8 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.kb-count-up-11295_f9366f-b8 .kb-count-up-number{font-size:64px;}}@media all and (max-width: 767px){.kb-count-up-11295_f9366f-b8 .kb-count-up-title{font-size:18px;}.kb-count-up-11295_f9366f-b8 .kb-count-up-number{font-size:50px;}}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-11295_f9366f-b8 kb-count-up\" data-start=\"0\" data-end=\"56090\" data-prefix=\"\u20ac\" data-suffix=\"M\" data-duration=\"1\" data-separator=\".\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">global turnover<\/p><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column11295_13de53-36 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11295_13de53-36 > .kt-inside-inner-col,.kadence-column11295_13de53-36 > .kt-inside-inner-col:before{border-top-left-radius:50%;border-top-right-radius:50%;border-bottom-right-radius:50%;border-bottom-left-radius:50%;}.kadence-column11295_13de53-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_13de53-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_13de53-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_13de53-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_13de53-36{text-align:center;}.kadence-column11295_13de53-36{position:relative;}.kadence-column11295_13de53-36, .kt-inside-inner-col > .kadence-column11295_13de53-36:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column11295_13de53-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_13de53-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_13de53-36\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-11295_5ba562-62 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.2;font-family:'Source Sans Pro';font-weight:300;text-transform:uppercase;padding-bottom:0px;margin-bottom:0px;}.kb-count-up-11295_5ba562-62 .kb-count-up-title{text-align:center;}.kb-count-up-11295_5ba562-62 .kb-count-up-number{color:var(--primary);font-size:80px;font-family:Raleway;font-weight:500;}@media all and (max-width: 1024px){.kb-count-up-11295_5ba562-62 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.kb-count-up-11295_5ba562-62 .kb-count-up-number{font-size:64px;}}@media all and (max-width: 767px){.kb-count-up-11295_5ba562-62 .kb-count-up-title{font-size:18px;}.kb-count-up-11295_5ba562-62 .kb-count-up-number{font-size:50px;}}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-11295_5ba562-62 kb-count-up\" data-start=\"0\" data-end=\"434\" data-prefix=\"+\" data-suffix=\"\" data-duration=\"1\" data-separator=\".\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">companies<\/p><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column11295_882434-56 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11295_882434-56 > .kt-inside-inner-col,.kadence-column11295_882434-56 > .kt-inside-inner-col:before{border-top-left-radius:50%;border-top-right-radius:50%;border-bottom-right-radius:50%;border-bottom-left-radius:50%;}.kadence-column11295_882434-56 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_882434-56 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_882434-56 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_882434-56 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_882434-56{text-align:center;}.kadence-column11295_882434-56{position:relative;}.kadence-column11295_882434-56, .kt-inside-inner-col > .kadence-column11295_882434-56:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column11295_882434-56 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_882434-56 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_882434-56\"><div class=\"kt-inside-inner-col\"><style>.kb-count-up-11295_74a5f4-c3 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.2;font-family:'Source Sans Pro';font-weight:300;text-transform:uppercase;padding-bottom:0px;margin-bottom:0px;}.kb-count-up-11295_74a5f4-c3 .kb-count-up-title{text-align:center;}.kb-count-up-11295_74a5f4-c3 .kb-count-up-number{color:var(--primary);font-size:80px;font-family:Raleway;font-weight:500;}@media all and (max-width: 1024px){.kb-count-up-11295_74a5f4-c3 .kb-count-up-title{font-size:var(--global-kb-font-size-md, 1.25rem);}}@media all and (max-width: 1024px){.kb-count-up-11295_74a5f4-c3 .kb-count-up-number{font-size:64px;}}@media all and (max-width: 767px){.kb-count-up-11295_74a5f4-c3 .kb-count-up-title{font-size:18px;}.kb-count-up-11295_74a5f4-c3 .kb-count-up-number{font-size:50px;}}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-11295_74a5f4-c3 kb-count-up\" data-start=\"0\" data-end=\"96305\" data-prefix=\"+\" data-suffix=\"\" data-duration=\"1\" data-separator=\".\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><p class=\"kb-count-up-title\">jobs worldwide<\/p><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/section>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_aadcf7-75{margin-bottom:0px;}.kb-row-layout-id11295_aadcf7-75 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_aadcf7-75 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_aadcf7-75 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1024px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_aadcf7-75 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_aadcf7-75 > .kt-row-column-wrap{padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_aadcf7-75 > .kt-row-column-wrap{padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_aadcf7-75 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:2px solid var(--base);border-bottom:2px solid var(--base);border-left:2px solid var(--base);}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col,.kadence-column11295_dfd18a-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{background-color:var(u002du002dwhite);}.kadence-column11295_dfd18a-32 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_dfd18a-32{text-align:center;}.kadence-column11295_dfd18a-32{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:2px solid var(--base);border-bottom:2px solid var(--base);border-left:2px solid var(--base);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_dfd18a-32 > .kt-inside-inner-col{border-top:0px solid var(--base);border-right:2px solid var(--base);border-bottom:2px solid var(--base);border-left:2px solid var(--base);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_dfd18a-32\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\">The Basque energy sector is noted for its high density of companies and professionals, with the whole supply chain being covered by some of the energy value chains. Its companies are also very important players internationally, taking part in the main energy projects worldwide and technologically leading key energy sectors with offshore wind power, tidal energy, the industrial development of hydrogen energy and smart networks, along with developing the application of key facilitator technologies in the energy sector, such as cybersecurity, AI, digitalisation, advanced materials, forecasting and simulation tools, etc. Thus, the Basque companies in the energy sector are present on the five continents in 69 countries with over 425 footholds abroad.  <\/p>\n\n\n\n<p class=\"has-text-align-left\">Furthermore, the Basque Country has implemented specific public policies and support programmes to drive the energy transition and to reduce the carbon footprint. Flagship projects in renewables and energy efficient, along with eco-innovation initiatives, are underway to advance towards a more sustainable and resilient energy model. The Basque Country and its technology centres are also involved in multiple international consortia and partnerships, which boost its ability to lead in the adoption of new global energy technologies and solutions.  <\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_8ae3c6-6b{margin-bottom:0px;}.kb-row-layout-id11295_8ae3c6-6b > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11295_8ae3c6-6b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11295_8ae3c6-6b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:1024px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id11295_8ae3c6-6b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_8ae3c6-6b > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id11295_8ae3c6-6b > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_8ae3c6-6b alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{display:flex;}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col,.kadence-column11295_a44aaa-fe > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column11295_a44aaa-fe{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_a44aaa-fe{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column11295_a44aaa-fe{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column11295_a44aaa-fe{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_a44aaa-fe > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_a44aaa-fe\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg\" alt=\"\" class=\"wp-image-9594\" style=\"width:300px\" srcset=\"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg 300w, https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n<style>.kadence-column11295_8c754e-bd > .kt-inside-inner-col{display:flex;}.kadence-column11295_8c754e-bd > .kt-inside-inner-col,.kadence-column11295_8c754e-bd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_8c754e-bd > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_8c754e-bd > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column11295_8c754e-bd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_8c754e-bd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_8c754e-bd{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column11295_8c754e-bd{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column11295_8c754e-bd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11295_8c754e-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_8c754e-bd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06, .wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06[data-kb-block=\"kb-adv-heading11295_de3ba4-06\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06[data-kb-block=\"kb-adv-heading11295_de3ba4-06\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06, .wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06[data-kb-block=\"kb-adv-heading11295_de3ba4-06\"]{font-size:22px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06, .wp-block-kadence-advancedheading.kt-adv-heading11295_de3ba4-06[data-kb-block=\"kb-adv-heading11295_de3ba4-06\"]{font-size:var(--global-kb-font-size-md, 1.25rem);text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading11295_de3ba4-06 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_de3ba4-06\"><strong>Meet our energy sector manager<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13, .wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13[data-kb-block=\"kb-adv-heading11295_8c154c-13\"]{margin-bottom:0px;font-size:24px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13[data-kb-block=\"kb-adv-heading11295_8c154c-13\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13, .wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13[data-kb-block=\"kb-adv-heading11295_8c154c-13\"]{font-size:22px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13, .wp-block-kadence-advancedheading.kt-adv-heading11295_8c154c-13[data-kb-block=\"kb-adv-heading11295_8c154c-13\"]{font-size:var(--global-kb-font-size-md, 1.25rem);text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading11295_8c154c-13 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_8c154c-13\"><strong>Lander Diego<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd, .wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd[data-kb-block=\"kb-adv-heading11295_4c999b-cd\"]{margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd[data-kb-block=\"kb-adv-heading11295_4c999b-cd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd, .wp-block-kadence-advancedheading.kt-adv-heading11295_4c999b-cd[data-kb-block=\"kb-adv-heading11295_4c999b-cd\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading11295_4c999b-cd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_4c999b-cd\"><em>Gestor Sector de Energ\u00eda<\/em><br><a href=\"mailto:ldiego@basquetreade.eus\">ldiego@basquetreade.eus<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_951fa3-93{margin-bottom:0px;}.kb-row-layout-id11295_951fa3-93 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11295_951fa3-93 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11295_951fa3-93 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:var(--global-kb-spacing-xxl, 5rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11295_951fa3-93 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_951fa3-93 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_951fa3-93 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_951fa3-93 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column11295_d72447-18 > .kt-inside-inner-col,.kadence-column11295_d72447-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_d72447-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_d72447-18 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_d72447-18 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_d72447-18 > .kt-inside-inner-col{background-color:var(u002du002dwhite);}.kadence-column11295_d72447-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_d72447-18{text-align:center;}.kadence-column11295_d72447-18{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_d72447-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_d72447-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_d72447-18\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11295_06cebc-25{margin-bottom:0px;}.kb-row-layout-id11295_06cebc-25 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11295_06cebc-25 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11295_06cebc-25 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(80% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(20% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id11295_06cebc-25 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11295_06cebc-25 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11295_06cebc-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11295_06cebc-25 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column11295_7b9d67-19 > .kt-inside-inner-col{display:flex;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col,.kadence-column11295_7b9d67-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_7b9d67-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_7b9d67-19{text-align:left;}.kadence-column11295_7b9d67-19{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_7b9d67-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kadence-column11295_7b9d67-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_7b9d67-19\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72, .wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72[data-kb-block=\"kb-adv-heading11295_7639f6-72\"]{margin-bottom:0px;text-align:left;font-size:var(--global-kb-font-size-xl, 3rem);font-weight:500;font-style:italic;font-family:'EB Garamond';}.wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72[data-kb-block=\"kb-adv-heading11295_7639f6-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72, .wp-block-kadence-advancedheading.kt-adv-heading11295_7639f6-72[data-kb-block=\"kb-adv-heading11295_7639f6-72\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading11295_7639f6-72 h2_border wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11295_7639f6-72\">Do you want to know the latest news about the sector?<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column11295_86ca4f-3a > .kt-inside-inner-col,.kadence-column11295_86ca4f-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11295_86ca4f-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11295_86ca4f-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column11295_86ca4f-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11295_86ca4f-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11295_86ca4f-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column11295_86ca4f-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11295_86ca4f-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11295_86ca4f-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns11295_ac17f5-bc{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:flex-end;align-items:center;}.kt-btns11295_ac17f5-bc .kt-button{font-weight:normal;font-style:normal;}.kt-btns11295_ac17f5-bc .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns11295_ac17f5-bc .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns11295_ac17f5-bc\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn11295_4ae99b-19.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn11295_4ae99b-19.kb-button{color:var(--primary);background:rgba(0,0,0,0);font-family:'Source Sans Pro';font-weight:600;text-transform:none;}.wp-block-kadence-advancedbtn .kb-btn11295_4ae99b-19.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11295_4ae99b-19.kb-button:focus{color:var(--primary);background:rgba(0,0,0,0);}<\/style><a class=\"kb-button kt-button button kb-btn11295_4ae99b-19 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"\/en\/sector\/energy\/\"><span class=\"kt-btn-inner-text\">See more<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div class=\"wp-block-ultimate-post-post-grid-parent ultp-post-grid-parent\" data-postid=\"11295\" data-grids=\"[{&quot;blockId&quot;:&quot;d93e20&quot;,&quot;name&quot;:&quot;ultimate-post_post-grid-1&quot;}]\" data-pagi=\"[]\"><div class=\"ultp-not-found-message\" role=\"alert\">No se encontr\u00f3 ning\u00fan resultado<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11332_c825db-9c{margin-bottom:0px;}.kb-row-layout-id11332_c825db-9c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11332_c825db-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11332_c825db-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11332_c825db-9c{background-image:url('https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/05\/banner-contacto-bg.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id11332_c825db-9c > .kt-row-layout-overlay{opacity:0.60;background-color:var(--white);}@media all and (max-width: 1024px){.kb-row-layout-id11332_c825db-9c > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11332_c825db-9c > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id11332_c825db-9c alignfull has-white-background-color kt-row-has-bg bt-btn-primary wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column11332_5294e2-38 > .kt-inside-inner-col{display:flex;}.kadence-column11332_5294e2-38 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11332_5294e2-38 > .kt-inside-inner-col,.kadence-column11332_5294e2-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11332_5294e2-38 > .kt-inside-inner-col{row-gap:16px;column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11332_5294e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11332_5294e2-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column11332_5294e2-38{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column11332_5294e2-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11332_5294e2-38{text-align:center;}.kadence-column11332_5294e2-38{position:relative;}@media all and (max-width: 1024px){.kadence-column11332_5294e2-38 > .kt-inside-inner-col{row-gap:24px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column11332_5294e2-38{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11332_5294e2-38 > .kt-inside-inner-col{row-gap:24px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column11332_5294e2-38{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11332_5294e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11332_5294e2-38 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f, .wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f[data-kb-block=\"kb-adv-heading11332_ab226c-8f\"]{margin-bottom:0px;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.6;font-weight:500;font-style:italic;font-family:'EB Garamond';}.wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f[data-kb-block=\"kb-adv-heading11332_ab226c-8f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f, .wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f[data-kb-block=\"kb-adv-heading11332_ab226c-8f\"]{line-height:1.2;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f, .wp-block-kadence-advancedheading.kt-adv-heading11332_ab226c-8f[data-kb-block=\"kb-adv-heading11332_ab226c-8f\"]{line-height:1.2;}}<\/style>\n<h2 class=\"kt-adv-heading11332_ab226c-8f h2_border_center_contacto wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11332_ab226c-8f\">How can we help you?<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading11332_471a35-12, .wp-block-kadence-advancedheading.kt-adv-heading11332_471a35-12[data-kb-block=\"kb-adv-heading11332_471a35-12\"]{max-width:700px;margin-right:auto;margin-left:auto;margin-bottom:8px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading11332_471a35-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11332_471a35-12[data-kb-block=\"kb-adv-heading11332_471a35-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h6 class=\"kt-adv-heading11332_471a35-12 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11332_471a35-12\">At Basque Trade &amp; Investment, we help you with your internationalisation process, whether you need <strong>personalised services<\/strong> and if you are looking for information to <strong>expand your company abroad<\/strong>.<\/h6>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns11332_40bd4f-4c{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:center;align-items:center;}.kt-btns11332_40bd4f-4c .kt-button{font-weight:normal;font-style:normal;}.kt-btns11332_40bd4f-4c .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns11332_40bd4f-4c .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns11332_40bd4f-4c\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button{color:var(--primary);background:rgba(255,255,255,0);font-family:'Source Sans Pro';font-weight:600;text-transform:uppercase;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;border-top:1px solid var(--primary);border-right:1px solid var(--primary);border-bottom:1px solid var(--primary);border-left:1px solid var(--primary);padding-top:8px;padding-right:24px;padding-bottom:8px;padding-left:24px;}.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:focus{color:var(--white);background:var(--primary);border-top-color:var(--primary);border-top-style:solid;border-right-color:var(--primary);border-right-style:solid;border-bottom-color:var(--primary);border-bottom-style:solid;border-left-color:var(--primary);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button{border-top:1px solid var(--primary);border-right:1px solid var(--primary);border-bottom:1px solid var(--primary);border-left:1px solid var(--primary);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:focus{border-top-color:var(--primary);border-top-style:solid;border-right-color:var(--primary);border-right-style:solid;border-bottom-color:var(--primary);border-bottom-style:solid;border-left-color:var(--primary);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button{border-top:1px solid var(--primary);border-right:1px solid var(--primary);border-bottom:1px solid var(--primary);border-left:1px solid var(--primary);}.wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11332_1cb2a5-7f.kb-button:focus{border-top-color:var(--primary);border-top-style:solid;border-right-color:var(--primary);border-right-style:solid;border-bottom-color:var(--primary);border-bottom-style:solid;border-left-color:var(--primary);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn11332_1cb2a5-7f kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"\/en\/contact\/\"><span class=\"kt-btn-inner-text\">CONTACT US<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Energy Service and specialty The energy sector is one of the strategic cornerstones of the technological and industrial development of the Basque Country, representing 9% of the industrial GDP and employing over 26,000 people in the Basque Country. The Basque companies of the sector cover a wide range, from generating solar and wind power to &#8230; <a title=\"Energy\" class=\"read-more\" href=\"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/specialist-and-sectoral-services\/energy\/\" aria-label=\"Read more about Energy\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":11420,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11295","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Energy - Basque Trade &amp; Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energy\" \/>\n<meta property=\"og:description\" content=\"Energy Service and specialty The energy sector is one of the strategic cornerstones of the technological and industrial development of the Basque Country, representing 9% of the industrial GDP and employing over 26,000 people in the Basque Country. The Basque companies of the sector cover a wide range, from generating solar and wind power to ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/\" \/>\n<meta property=\"og:site_name\" content=\"Basque Trade &amp; Investment\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T14:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/\",\"url\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/\",\"name\":\"Energy - Basque Trade &amp; Investment\",\"isPartOf\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg\",\"datePublished\":\"2024-05-14T15:49:24+00:00\",\"dateModified\":\"2025-01-23T14:43:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage\",\"url\":\"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg\",\"contentUrl\":\"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/basquetrade.spri.eus\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What we offer\",\"item\":\"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Specialist and sectoral services\",\"item\":\"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/specialist-and-sectoral-services\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Energy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/basquetrade.spri.eus\/#website\",\"url\":\"https:\/\/basquetrade.spri.eus\/\",\"name\":\"Basque Trade &amp; Investment\",\"description\":\"Agencia Vasca de Internacionalizaci\u00f3n \u2013 Basque Trade &amp; Investment\",\"publisher\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/basquetrade.spri.eus\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/basquetrade.spri.eus\/#organization\",\"name\":\"Basque Trade &amp; Investment\",\"url\":\"https:\/\/basquetrade.spri.eus\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/basquetrade.spri.eus\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2025\/04\/head-logo-BasqueTrade.jpg\",\"contentUrl\":\"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2025\/04\/head-logo-BasqueTrade.jpg\",\"width\":230,\"height\":100,\"caption\":\"Basque Trade &amp; Investment\"},\"image\":{\"@id\":\"https:\/\/basquetrade.spri.eus\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Energy - Basque Trade &amp; Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/","og_locale":"en_US","og_type":"article","og_title":"Energy","og_description":"Energy Service and specialty The energy sector is one of the strategic cornerstones of the technological and industrial development of the Basque Country, representing 9% of the industrial GDP and employing over 26,000 people in the Basque Country. The Basque companies of the sector cover a wide range, from generating solar and wind power to ... Read more","og_url":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/","og_site_name":"Basque Trade &amp; Investment","article_modified_time":"2025-01-23T14:43:31+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/","url":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/","name":"Energy - Basque Trade &amp; Investment","isPartOf":{"@id":"https:\/\/basquetrade.spri.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage"},"image":{"@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage"},"thumbnailUrl":"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg","datePublished":"2024-05-14T15:49:24+00:00","dateModified":"2025-01-23T14:43:31+00:00","breadcrumb":{"@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#primaryimage","url":"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg","contentUrl":"https:\/\/basquetrade.spri.eus\/wp-content\/uploads\/2024\/11\/Sector-energia_Lander-Diego.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/basquetrade.spri.eus\/servicios\/servicios-sectoriales-y-especializados\/energia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/basquetrade.spri.eus\/en\/"},{"@type":"ListItem","position":2,"name":"What we offer","item":"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/"},{"@type":"ListItem","position":3,"name":"Specialist and sectoral services","item":"https:\/\/basquetrade.spri.eus\/en\/what-we-offer\/specialist-and-sectoral-services\/"},{"@type":"ListItem","position":4,"name":"Energy"}]},{"@type":"WebSite","@id":"https:\/\/basquetrade.spri.eus\/#website","url":"https:\/\/basquetrade.spri.eus\/","name":"Basque Trade &amp; Investment","description":"Agencia Vasca de Internacionalizaci\u00f3n \u2013 Basque Trade &amp; Investment","publisher":{"@id":"https:\/\/basquetrade.spri.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basquetrade.spri.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basquetrade.spri.eus\/#organization","name":"Basque Trade &amp; Investment","url":"https:\/\/basquetrade.spri.eus\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basquetrade.spri.eus\/#\/schema\/logo\/image\/","url":"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2025\/04\/head-logo-BasqueTrade.jpg","contentUrl":"https:\/\/basquetrade.spri.eus\/\/wp-content\/uploads\/2025\/04\/head-logo-BasqueTrade.jpg","width":230,"height":100,"caption":"Basque Trade &amp; Investment"},"image":{"@id":"https:\/\/basquetrade.spri.eus\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/pages\/11295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/comments?post=11295"}],"version-history":[{"count":0,"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/pages\/11295\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/pages\/11420"}],"wp:attachment":[{"href":"https:\/\/basquetrade.spri.eus\/en\/wp-json\/wp\/v2\/media?parent=11295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}